{"id":41,"date":"2020-09-23T10:41:25","date_gmt":"2020-09-23T07:41:25","guid":{"rendered":"https:\/\/ebil.gr\/en\/?page_id=41"},"modified":"2024-01-15T09:09:47","modified_gmt":"2024-01-15T06:09:47","slug":"home-en","status":"publish","type":"page","link":"https:\/\/ebil.gr\/en\/","title":{"rendered":"HOME"},"content":{"rendered":"\t<section class=\"section dark\" id=\"section_1692220034\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n  <div class=\"banner has-hover hide-for-medium\" id=\"banner-1062635501\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-961142365\" class=\"text-box banner-layer x5 md-x15 lg-x15 y10 md-y65 lg-y65 res-text\">\n                     <div data-animate=\"fadeInLeft\">           <div class=\"text dark text-shadow-1\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2><span data-text-color=\"primary\">SOLAR SYSTEMS<\/span><\/h2>\n              <\/div>\n           <\/div>\n       <\/div>                     \n<style>\n#text-box-961142365 {\n  width: 59%;\n}\n#text-box-961142365 .text {\n  font-size: 47%;\n}\n@media (min-width:550px) {\n  #text-box-961142365 {\n    width: 30%;\n  }\n  #text-box-961142365 .text {\n    font-size: 60%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-961142365 {\n    width: 37%;\n  }\n  #text-box-961142365 .text {\n    font-size: 98%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1062635501 {\n  padding-top: 600px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-1062635501 .bg.bg-loaded {\n  background-image: url(https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/ebial-banner-5.jpg);\n}\n#banner-1062635501 .bg {\n  background-position: 0% 0%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover show-for-small\" id=\"banner-1075340354\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-441036684\" class=\"text-box banner-layer x5 md-x15 lg-x15 y50 md-y65 lg-y65 res-text\">\n                     <div data-animate=\"fadeInLeft\">           <div class=\"text dark text-shadow-1\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3>\u039f \u03ae\u03bb\u03b9\u03bf\u03c2 \u03b4\u03bf\u03c5\u03bb\u03b5\u03cd\u03b5\u03b9 \u03b3\u03b9\u03b1 \u03cc\u03bb\u03bf\u03c5\u03c2!<br \/>\n<span data-text-color=\"primary\">\u03ba\u03b1\u03b9 \u03c6\u03c5\u03c3\u03b9\u03ba\u03ac \u03b3\u03b9\u03b1 \u03b5\u03c3\u03ac\u03c2!<\/span><\/h3>\n              <\/div>\n           <\/div>\n       <\/div>                     \n<style>\n#text-box-441036684 {\n  width: 59%;\n}\n#text-box-441036684 .text {\n  font-size: 47%;\n}\n@media (min-width:550px) {\n  #text-box-441036684 {\n    width: 30%;\n  }\n  #text-box-441036684 .text {\n    font-size: 60%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-441036684 {\n    width: 37%;\n  }\n  #text-box-441036684 .text {\n    font-size: 98%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1075340354 {\n  padding-top: 69%;\n  background-color: rgb(255, 255, 255);\n}\n#banner-1075340354 .bg.bg-loaded {\n  background-image: url(https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/10\/banner-mobile-min.jpg);\n}\n#banner-1075340354 .bg {\n  background-position: 0% 0%;\n}\n@media (min-width:550px) {\n  #banner-1075340354 {\n    padding-top: 600px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1692220034 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 100px;\n  background-color: rgb(246, 246, 246);\n}\n@media (min-width:550px) {\n  #section_1692220034 {\n    padding-top: 0px;\n    padding-bottom: 0px;\n    min-height: 0px;\n  }\n}\n@media (min-width:850px) {\n  #section_1692220034 {\n    min-height: 600px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1089227193\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-center\"  id=\"row-229707356\">\n\n\t<div id=\"col-686815239\" class=\"col medium-10 small-12 large-8\"  >\n\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<h3><span style=\"font-size: 200%;\">Solar Systems<\/span><\/h3>\n<p><strong>50 YEARS<\/strong> of continuous research and development of its technical infrastructure, have led the company to the forefront. The endurance and reliability of the <strong>THOUSANDS<\/strong> of appliances of all types it has installed, have established the company as the number one choice for consumers.<\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-equal align-center\"  id=\"row-1757798388\">\n\n\t<div id=\"col-604092921\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner box-shadow-2-hover\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/ebil.gr\/en\/thermosiphonas-120\/\"  >\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"500\" src=\"https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/product1-8.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/product1-8.jpg 400w, https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/product1-8-240x300.jpg 240w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>SOLAR HEATER 120 L<\/h4>\n<a href=\"https:\/\/ebil.gr\/en\/thermosiphonas-120\/\" target=\"_self\" class=\"button secondary lowercase expand\"  style=\"border-radius:8px;\">\n    <span>Read more<\/span>\n  <\/a>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2005638617\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner box-shadow-2-hover\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/ebil.gr\/en\/thermosiphonas-150\/\"  >\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"500\" src=\"https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/product2-8.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/product2-8.jpg 400w, https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/product2-8-240x300.jpg 240w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>SOLAR HEATER 150 L<\/h4>\n<a href=\"https:\/\/ebil.gr\/en\/thermosiphonas-150\/\" target=\"_self\" class=\"button secondary lowercase expand\"  style=\"border-radius:8px;\">\n    <span>Read more<\/span>\n  <\/a>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-872596904\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner box-shadow-2-hover\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/ebil.gr\/en\/thermosiphonas-200\/\"  >\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"500\" src=\"https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/product3-8.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/product3-8.jpg 400w, https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/product3-8-240x300.jpg 240w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>SOLAR HEATER 200 L<\/h4>\n<a href=\"https:\/\/ebil.gr\/en\/thermosiphonas-200\/\" target=\"_self\" class=\"button secondary lowercase expand\"  style=\"border-radius:8px;\">\n    <span>Read more<\/span>\n  <\/a>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1757798388 > .col > .col-inner {\n  padding: 10px 10px 10px 10px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1089227193 {\n  padding-top: 50px;\n  padding-bottom: 50px;\n  background-color: rgb(246, 246, 246);\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1337938153\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-large align-middle align-center\"  id=\"row-257698048\">\n\n\t<div id=\"col-177049532\" class=\"col medium-10 small-12 large-7\"  data-animate=\"fadeInLeft\">\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1170573294\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"https:\/\/ebil.gr\/en\/thermosiphones\/\"  ><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-1440127930\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1440127930 {\n  width: 60%;\n}\n#text-box-1440127930 .text {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1170573294 {\n  padding-top: 500px;\n}\n#banner-1170573294 .bg.bg-loaded {\n  background-image: url(https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/BOILER-2-min.png);\n}\n#banner-1170573294 .bg {\n  background-position: 34% 30%;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-171355567\" class=\"col medium-10 small-12 large-5\"  data-animate=\"fadeInRight\">\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-490042854\">\n\n\t<div id=\"col-2112063507\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3><span style=\"font-size: 200%;\">Water Heaters<\/span><\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t<div id=\"gap-642735860\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-642735860 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n<p>We offer a great variety of Water Heaters.<\/p>\n<a href=\"https:\/\/ebil.gr\/en\/thermosiphones\/\" target=\"_self\" class=\"button alert is-small lowercase\"  style=\"border-radius:8px;\">\n    <span>See all products<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<style>\n#row-490042854 > .col > .col-inner {\n  padding: 0px 0px 10px 0px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1337938153 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1552497260\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-large align-middle align-center\"  id=\"row-546888296\">\n\n\t<div id=\"col-1173878081\" class=\"col medium-10 small-12 large-7\"  data-animate=\"fadeInLeft\">\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1777591103\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"https:\/\/ebil.gr\/en\/boilers\/\"  ><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-452089165\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-452089165 {\n  width: 60%;\n}\n#text-box-452089165 .text {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1777591103 {\n  padding-top: 500px;\n}\n#banner-1777591103 .bg.bg-loaded {\n  background-image: url(https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/BOILER-min.png);\n}\n#banner-1777591103 .bg {\n  background-position: 34% 30%;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-574723931\" class=\"col medium-10 small-12 large-5\"  data-animate=\"fadeInRight\">\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-845916402\">\n\n\t<div id=\"col-1031263858\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3><span style=\"font-size: 200%;\">Boilers<\/span><\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t<div id=\"gap-1712399393\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1712399393 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n<p>The endurance and reliability of the\u00a0<strong>THOUSANDS<\/strong>\u00a0of appliances of all types it has installed, have established the company as the number one choice for consumers.<\/p>\n<a href=\"https:\/\/ebil.gr\/en\/boilers\/\" target=\"_self\" class=\"button alert is-small lowercase\"  style=\"border-radius:8px;\">\n    <span>See all products<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<style>\n#row-845916402 > .col > .col-inner {\n  padding: 0px 0px 10px 0px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1552497260 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section dark\" id=\"section_1343533646\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-413413431\">\n\n\t<div id=\"col-2003816499\" class=\"col medium-12 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>9000 sq.m. of Facilities<\/h2>\n<p><strong>EBIL S.A. CONTINUES TO AIM HIGH<\/strong>. It invests in state-of-the-art technology.<\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1603109143\" class=\"col medium-12 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-287909802\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-287909802 {\n  padding-top: 40px;\n}\n@media (min-width:850px) {\n  #gap-287909802 {\n    padding-top: 100px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1343533646 {\n  padding-top: 50px;\n  padding-bottom: 50px;\n  background-color: rgb(9, 105, 176);\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_2030345202\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1904330371\">\n\n\t<div id=\"col-434961730\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row align-center\"  id=\"row-1492243990\">\n\n\t<div id=\"col-21605641\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-shade dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/ebil.gr\/en\/company\/\"  >\t\t\t<div class=\"image-overlay-add image-cover\" style=\"padding-top:80%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/ebil-banner-3-min.jpg\" class=\"attachment- size-\" alt=\"\u0395\u0392\u0397\u039b \u0391.\u0395. \u0397\u03bb\u03b9\u03b1\u03ba\u03ac, \u0398\u03b5\u03c1\u03bc\u03bf\u03c3\u03af\u03c6\u03c9\u03bd\u03b5\u03c2, \u0397\u03bb\u03b5\u03ba\u03c4\u03c1\u03bf\u03bc\u03c0\u03cc\u03b9\u03bb\u03b5\u03c1 - \u039a\u03b1\u03c4\u03b5\u03c1\u03af\u03bd\u03b7, \u03a0\u03b9\u03b5\u03c1\u03af\u03b1\" srcset=\"https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/ebil-banner-3-min.jpg 600w, https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/ebil-banner-3-min-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.25)\"><\/div>\t\t\t\t<div class=\"shade\"><\/div>\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-left\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4><span style=\"font-size: 150%;\">Factory<\/span><\/h4>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-524995495\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-shade dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/ebil.gr\/en\/company\/\"  >\t\t\t<div class=\"image-overlay-add image-cover\" style=\"padding-top:80%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/ebil-banner-2-min-1.jpg\" class=\"attachment- size-\" alt=\"\u0395\u0392\u0397\u039b \u0391.\u0395. \u0397\u03bb\u03b9\u03b1\u03ba\u03ac, \u0398\u03b5\u03c1\u03bc\u03bf\u03c3\u03af\u03c6\u03c9\u03bd\u03b5\u03c2, \u0397\u03bb\u03b5\u03ba\u03c4\u03c1\u03bf\u03bc\u03c0\u03cc\u03b9\u03bb\u03b5\u03c1 - \u039a\u03b1\u03c4\u03b5\u03c1\u03af\u03bd\u03b7, \u03a0\u03b9\u03b5\u03c1\u03af\u03b1\" srcset=\"https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/ebil-banner-2-min-1.jpg 600w, https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/ebil-banner-2-min-1-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.25)\"><\/div>\t\t\t\t<div class=\"shade\"><\/div>\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-left\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4><\/h4>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-789026931\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-shade dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/ebil.gr\/en\/company\/\"  >\t\t\t<div class=\"image-overlay-add image-cover\" style=\"padding-top:80%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/ebil-banner-4-min-1.jpg\" class=\"attachment- size-\" alt=\"\u0395\u0392\u0397\u039b \u0391.\u0395. \u0397\u03bb\u03b9\u03b1\u03ba\u03ac, \u0398\u03b5\u03c1\u03bc\u03bf\u03c3\u03af\u03c6\u03c9\u03bd\u03b5\u03c2, \u0397\u03bb\u03b5\u03ba\u03c4\u03c1\u03bf\u03bc\u03c0\u03cc\u03b9\u03bb\u03b5\u03c1 - \u039a\u03b1\u03c4\u03b5\u03c1\u03af\u03bd\u03b7, \u03a0\u03b9\u03b5\u03c1\u03af\u03b1\" srcset=\"https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/ebil-banner-4-min-1.jpg 600w, https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/ebil-banner-4-min-1-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.25)\"><\/div>\t\t\t\t<div class=\"shade\"><\/div>\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-left\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4><\/h4>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-219061689\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-shade dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/ebil.gr\/en\/company\/\"  >\t\t\t<div class=\"image-overlay-add image-cover\" style=\"padding-top:80%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/ebil-banner-1-min-1.jpg\" class=\"attachment- size-\" alt=\"\u0395\u0392\u0397\u039b \u0391.\u0395. \u0397\u03bb\u03b9\u03b1\u03ba\u03ac, \u0398\u03b5\u03c1\u03bc\u03bf\u03c3\u03af\u03c6\u03c9\u03bd\u03b5\u03c2, \u0397\u03bb\u03b5\u03ba\u03c4\u03c1\u03bf\u03bc\u03c0\u03cc\u03b9\u03bb\u03b5\u03c1 - \u039a\u03b1\u03c4\u03b5\u03c1\u03af\u03bd\u03b7, \u03a0\u03b9\u03b5\u03c1\u03af\u03b1\" srcset=\"https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/ebil-banner-1-min-1.jpg 600w, https:\/\/ebil.gr\/en\/wp-content\/uploads\/2020\/09\/ebil-banner-1-min-1-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(0, 0, 0, 0.25)\"><\/div>\t\t\t\t<div class=\"shade\"><\/div>\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-left\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4><\/h4>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-438016247\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-331797330\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-331797330 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\n<style>\n#col-434961730 > .col-inner {\n  margin: -175px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2030345202 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-41","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ebil.gr\/en\/wp-json\/wp\/v2\/pages\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ebil.gr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ebil.gr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ebil.gr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ebil.gr\/en\/wp-json\/wp\/v2\/comments?post=41"}],"version-history":[{"count":4,"href":"https:\/\/ebil.gr\/en\/wp-json\/wp\/v2\/pages\/41\/revisions"}],"predecessor-version":[{"id":1195,"href":"https:\/\/ebil.gr\/en\/wp-json\/wp\/v2\/pages\/41\/revisions\/1195"}],"wp:attachment":[{"href":"https:\/\/ebil.gr\/en\/wp-json\/wp\/v2\/media?parent=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}